{"id":284,"count":1,"description":"","link":"https:\/\/freepalestine.one\/fr\/tag\/autorite-palestinienne\/","name":"Autorit\u00e9 palestinienne","slug":"autorite-palestinienne","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/freepalestine.one\/fr\/wp-json\/wp\/v2\/tags\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freepalestine.one\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/freepalestine.one\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/freepalestine.one\/fr\/wp-json\/wp\/v2\/posts?tags=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}